{"id":354,"date":"2023-05-24T11:27:53","date_gmt":"2023-05-24T11:27:53","guid":{"rendered":"http:\/\/www.facilita.al.gov.br\/?page_id=354"},"modified":"2025-08-25T23:51:47","modified_gmt":"2025-08-25T23:51:47","slug":"publicacoes","status":"publish","type":"page","link":"https:\/\/www.facilita.al.gov.br\/home\/publicacoes\/","title":{"rendered":"Publica\u00e7\u00f5es"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pages\/junta-comercial.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-354","page","type-page","status-publish","hentry"],"acf":{"servicos":[{"titulo":"Anota\u00e7\u00e3o de Publica\u00e7\u00f5es de Atos de Sociedade","conteudo":"Trata-se da anota\u00e7\u00e3o de publica\u00e7\u00f5es de atos de sociedade","btn":"https:\/\/%s.facilita.al.gov.br\/evento-exclusivo\/coletar-dados-consumo\/709","parametros":"{'eventos-junta':'menu-publicacoes','tp-evento':'ex','evento[]':'709'}","method":"GET","mensagem_modal":"","acesso":["visivel_todos"]},{"titulo":"Arquivamento de Publica\u00e7\u00f5es de Atos de Sociedade","conteudo":"Trata-se do arquivamento de publica\u00e7\u00f5es de atos de sociedade","btn":"https:\/\/%s.facilita.al.gov.br\/evento-exclusivo\/coletar-dados-consumo\/708","parametros":"{'eventos-junta':'menu-publicacoes','tp-evento':'ex','evento[]':'708'}","method":"GET","mensagem_modal":"","acesso":["visivel_todos"]},{"titulo":"Publica\u00e7\u00f5es Relativas a Agentes Auxiliares do Com\u00e9rcio","conteudo":"","btn":"https:\/\/%s.facilita.al.gov.br\/evento-exclusivo\/capa-processo\/","parametros":"{'eventos-junta':'menu-publicacoes','tp-evento':'cpp','ato-siarco[]':'{417}','evento-siarco':'417'}","method":"GET","mensagem_modal":"","acesso":["visivel_todos"]}]},"_links":{"self":[{"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/pages\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":0,"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/pages\/354\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.facilita.al.gov.br\/home\/wp-json\/wp\/v2\/media?parent=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}